{"id":4755,"date":"2017-11-17T15:53:55","date_gmt":"2017-11-17T15:53:55","guid":{"rendered":"http:\/\/umwtheatre.org\/archives\/wp-content\/uploads\/2017\/11\/c38355_fbc8fca6a2f643408c7f6854bd6d4d5fmv2_d_5760_3840_s_4_2.jpg"},"modified":"2018-03-20T17:50:19","modified_gmt":"2018-03-20T17:50:19","slug":"c38355_fbc8fca6a2f643408c7f6854bd6d4d5fmv2_d_5760_3840_s_4_2","status":"inherit","type":"attachment","link":"https:\/\/umwtheatre.org\/archives\/2017\/12\/04\/macbeth\/c38355_fbc8fca6a2f643408c7f6854bd6d4d5fmv2_d_5760_3840_s_4_2\/","title":{"rendered":""},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-4755","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/umwtheatre.org\/archives\/wp-content\/uploads\/2017\/11\/c38355_fbc8fca6a2f643408c7f6854bd6d4d5fmv2_d_5760_3840_s_4_2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/umwtheatre.org\/archives\/wp-content\/uploads\/2017\/11\/c38355_fbc8fca6a2f643408c7f6854bd6d4d5fmv2_d_5760_3840_s_4_2-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/umwtheatre.org\/archives\/wp-content\/uploads\/2017\/11\/c38355_fbc8fca6a2f643408c7f6854bd6d4d5fmv2_d_5760_3840_s_4_2-300x200.jpg 300w, https:\/\/umwtheatre.org\/archives\/wp-content\/uploads\/2017\/11\/c38355_fbc8fca6a2f643408c7f6854bd6d4d5fmv2_d_5760_3840_s_4_2-768x512.jpg 768w, https:\/\/umwtheatre.org\/archives\/wp-content\/uploads\/2017\/11\/c38355_fbc8fca6a2f643408c7f6854bd6d4d5fmv2_d_5760_3840_s_4_2-1024x682.jpg 1024w, https:\/\/umwtheatre.org\/archives\/wp-content\/uploads\/2017\/11\/c38355_fbc8fca6a2f643408c7f6854bd6d4d5fmv2_d_5760_3840_s_4_2.jpg 1172w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1172,"height":781,"file":"2017\/11\/c38355_fbc8fca6a2f643408c7f6854bd6d4d5fmv2_d_5760_3840_s_4_2.jpg","sizes":{"thumbnail":{"file":"c38355_fbc8fca6a2f643408c7f6854bd6d4d5fmv2_d_5760_3840_s_4_2-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/umwtheatre.org\/archives\/wp-content\/uploads\/2017\/11\/c38355_fbc8fca6a2f643408c7f6854bd6d4d5fmv2_d_5760_3840_s_4_2-150x150.jpg"},"medium":{"file":"c38355_fbc8fca6a2f643408c7f6854bd6d4d5fmv2_d_5760_3840_s_4_2-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/umwtheatre.org\/archives\/wp-content\/uploads\/2017\/11\/c38355_fbc8fca6a2f643408c7f6854bd6d4d5fmv2_d_5760_3840_s_4_2-300x200.jpg"},"medium_large":{"file":"c38355_fbc8fca6a2f643408c7f6854bd6d4d5fmv2_d_5760_3840_s_4_2-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/umwtheatre.org\/archives\/wp-content\/uploads\/2017\/11\/c38355_fbc8fca6a2f643408c7f6854bd6d4d5fmv2_d_5760_3840_s_4_2-768x512.jpg"},"large":{"file":"c38355_fbc8fca6a2f643408c7f6854bd6d4d5fmv2_d_5760_3840_s_4_2-1024x682.jpg","width":1024,"height":682,"mime_type":"image\/jpeg","source_url":"https:\/\/umwtheatre.org\/archives\/wp-content\/uploads\/2017\/11\/c38355_fbc8fca6a2f643408c7f6854bd6d4d5fmv2_d_5760_3840_s_4_2-1024x682.jpg"},"full":{"file":"c38355_fbc8fca6a2f643408c7f6854bd6d4d5fmv2_d_5760_3840_s_4_2.jpg","width":1172,"height":781,"mime_type":"image\/jpeg","source_url":"https:\/\/umwtheatre.org\/archives\/wp-content\/uploads\/2017\/11\/c38355_fbc8fca6a2f643408c7f6854bd6d4d5fmv2_d_5760_3840_s_4_2.jpg"}},"image_meta":{"aperture":"2.8","credit":"","camera":"Canon EOS 5D Mark III","caption":"","created_timestamp":"1492047296","copyright":"","focal_length":"89","iso":"10000","shutter_speed":"0.00625","title":"","orientation":"0","keywords":[]}},"post":4742,"source_url":"https:\/\/umwtheatre.org\/archives\/wp-content\/uploads\/2017\/11\/c38355_fbc8fca6a2f643408c7f6854bd6d4d5fmv2_d_5760_3840_s_4_2.jpg","_links":{"self":[{"href":"https:\/\/umwtheatre.org\/archives\/wp-json\/wp\/v2\/media\/4755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/umwtheatre.org\/archives\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/umwtheatre.org\/archives\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/umwtheatre.org\/archives\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/umwtheatre.org\/archives\/wp-json\/wp\/v2\/comments?post=4755"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":4742,"href":"https:\/\/umwtheatre.org\/archives\/wp-json\/wp\/v2\/posts\/4742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}